{"id":39239,"date":"2024-01-23T10:31:42","date_gmt":"2024-01-23T09:31:42","guid":{"rendered":"https:\/\/stage.aerothrive.com\/sobre-nosotros\/"},"modified":"2026-05-06T17:16:15","modified_gmt":"2026-05-06T15:16:15","slug":"sobre-nosotros","status":"publish","type":"page","link":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"\n<div  class=\" f4-block-hero-header is-layout-constrained has-content alignfull\"   >\n    <div class=\"block-media\">\n            <\/div>\n    <div class=\"block-content\">\n            <div class=\"acf-innerblocks-container\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading is-style-tagline\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Servicios de apoyo a la aviaci\u00f3n<\/mark><\/h1>\n\n\n\n<h2 class=\"wp-block-heading is-style-h1\">AEROTHRIVE. Excelencia global en aviaci\u00f3n. <\/h2>\n\n\n\n<p class=\"is-style-h5\">Sus copilotos de referencia: un socio de confianza para soluciones de seguridad, calidad y cumplimiento.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n<\/div>    <\/div>\n<\/div>\n\n<div class=\"wp-block-group alignfull has-white-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--medium);padding-bottom:0\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Acelerando la aviaci\u00f3n. Airbourne en Alemania. <\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Nuestro equipo, rico en experiencia y rebosante de entusiasmo, no es solo un grupo de profesionales: somos aut\u00e9nticos Aviationeers. Con nuestra amplia experiencia pr\u00e1ctica, acumulada durante varias d\u00e9cadas, nos especializamos en guiarle en cada fase de su trayectoria en la aviaci\u00f3n. Perm\u00edtanos conducirle hacia la experiencia de vuelo fluida y emocionante que busca. En AEROTHRIVE, no se trata solo de alcanzar nuevas cotas; se trata de redefinir el viaje.\u201d   <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element\" style=\"margin-top:var(--wp--preset--spacing--medium);margin-bottom:var(--wp--preset--spacing--default)\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading is-style-default\">Presentaci\u00f3n de la empresa<\/h3>\n\n\n\n<p class=\"is-style-p-large\">Conozca en detalle los antecedentes de nuestro grupo de empresas, nuestro equipo de expertos globales, nuestros servicios, acreditaciones y reconocimiento en los medios: \u00a1eche un vistazo a nuestro folleto corporativo!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/2026_01_20-AT-Intro-R16a.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Folleto<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1024x575.jpg\" alt=\"\" class=\"wp-image-38425 size-teaser-big\" style=\"object-position:50% 50%\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1024x575.jpg 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-300x168.jpg 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1536x862.jpg 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-2048x1150.jpg 2048w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-528x297.jpg 528w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1920x1080.jpg 1920w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-532x299.jpg 532w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element\" style=\"margin-top:var(--wp--preset--spacing--medium);margin-bottom:var(--wp--preset--spacing--default)\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"581\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/Media2-1024x581.jpg\" alt=\"\" class=\"wp-image-38366 size-teaser-big\" style=\"object-position:50% 50%\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/Media2-1024x581.jpg 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/Media2-300x170.jpg 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/Media2-1536x872.jpg 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/Media2-2048x1162.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading is-style-default\">Art\u00edculos en medios<\/h3>\n\n\n\n<p class=\"is-style-p-large\">Conozca en detalle los antecedentes de nuestro grupo de empresas, nuestro equipo de expertos globales, nuestros servicios, acreditaciones y reconocimiento en los medios: \u00a1eche un vistazo a nuestro folleto corporativo!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/aerothrive.com\/es\/sala-de-prensa\/\">M\u00e1s<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div  class=\" f4-block-team-slider alignfull has-background has-white-background-color\"   >\n\n\n\n\n\n    <div class=\"block-inner\">\n        <div class=\"f4_ribbon-slider team-slider\" id=\"ribbon-slider_6a9837447c1b8\"  data-ribbon-slider data-options=\"[]\"> <div data-container>    <div data-items-wrapper>        <div data-items>\t\t<div data-item class=\"\"   data-id=\"0\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/08\/Patrick_Lutz_Portrait_plain-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Patrick<\/div><div class=\"team_member__description\">Patrick cuenta con una trayectoria exitosa de m\u00e1s de 25 a\u00f1os en gesti\u00f3n de seguridad, calidad y cumplimiento en aviaci\u00f3n, incluyendo una amplia experiencia como Auditor L\u00edder IOSA, Auditor L\u00edder SARPcheck y Auditor de Aviaci\u00f3n. Ha dirigido y realizado m\u00e1s de 250 auditor\u00edas en m\u00e1s de 140 pa\u00edses para m\u00e1s de 50 aerol\u00edneas. Patrick es tambi\u00e9n un instructor apasionado para formaciones en las \u00e1reas de auditor\u00eda, calidad, seguridad y cumplimiento, y ha dirigido y realizado proyectos de consultor\u00eda en todo el mundo. Dedic\u00f3 m\u00e1s de una d\u00e9cada de su carrera al cargo de Director General en el Grupo Lufthansa, donde transform\u00f3 la empresa subsidiaria AQS en una organizaci\u00f3n de auditor\u00eda IOSA de IATA l\u00edder a nivel mundial. Pero, despu\u00e9s de todo, Patrick es simplemente un entusiasta de la aviaci\u00f3n.    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/08\/Patrick_Lutz_Portrait_plain-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"1\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"648\" height=\"800\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/c.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/c.png 648w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/c-243x300.png 243w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Jan-Lou<\/div><div class=\"team_member__description\">Jan-Lou, ciudadano franc\u00e9s, destaca como Auditor L\u00edder y Evaluador IOSA basado en riesgos. Con m\u00e1s de 30 a\u00f1os de experiencia en aviaci\u00f3n, Jan-Lou ha gestionado con \u00e9xito diversos roles de auditor\u00eda y cumplimiento normativo. Sus puestos incluyen Examinador Senior de Ingeniero de Vuelo e Instructor de CRM, lo que demuestra su experiencia en operaciones de vuelo y formaci\u00f3n en factores humanos. Jan-Lou ha realizado m\u00e1s de 150 auditor\u00edas IOSA, ha establecido sistemas de gesti\u00f3n de competencias y ha proporcionado consultor\u00eda para importantes empresas de aviaci\u00f3n. Con dominio del ingl\u00e9s y m\u00faltiples certificaciones, Jan-Lou es un activo de gran valor en seguridad a\u00e9rea, cumplimiento normativo y gesti\u00f3n de la calidad. (Freelance)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"648\" height=\"800\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/c.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/c.png 648w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/c-243x300.png 243w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"2\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/PH-freigestellt-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Pierre-Henri<\/div><div class=\"team_member__description\">Pierre-Henri, de Par\u00eds, destaca como subdirector general y auditor acreditado IOSA RBI. Con m\u00e1s de 25 a\u00f1os de amplia experiencia en aviaci\u00f3n, Pierre-Henri ha liderado con \u00e9xito diversos programas de cumplimiento y seguridad. Entre sus funciones se incluyen las de responsable del Programa de Seguridad de Vuelo y jefe del Sistema de Informaci\u00f3n QMS\/SMS, lo que demuestra su experiencia en gesti\u00f3n de riesgos y liderazgo estrat\u00e9gico de proyectos. Pierre-Henri ha gestionado programas de auditor\u00eda de aerol\u00edneas a gran escala e implantado sistemas de gesti\u00f3n integrados, poniendo de manifiesto su liderazgo en seguridad a\u00e9rea. Con dominio del ingl\u00e9s y varios t\u00edtulos superiores, Pierre-Henri es un activo de gran valor en la gesti\u00f3n de la seguridad a\u00e9rea y del cumplimiento normativo. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/PH-freigestellt-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"3\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"583\" height=\"721\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-CV-Linkedin-2-Kopie.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-CV-Linkedin-2-Kopie.png 583w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-CV-Linkedin-2-Kopie-243x300.png 243w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Steven<\/div><div class=\"team_member__description\">Steven destaca como responsable de Supervisi\u00f3n de Seguridad y Cumplimiento y auditor principal de aviaci\u00f3n IOSA. Con una amplia experiencia en operaciones de vuelo y en tierra, Steven ha liderado con \u00e9xito diversos proyectos de aviaci\u00f3n. Entre sus funciones se incluyen la creaci\u00f3n de la primera aerol\u00ednea de helic\u00f3pteros en Mayotte y la gesti\u00f3n de la seguridad y el cumplimiento para m\u00faltiples aerol\u00edneas. La experiencia de Steven abarca auditor\u00edas EASA e IOSA, documentaci\u00f3n operativa y gesti\u00f3n de proyectos. Habla con fluidez varios idiomas y cuenta con titulaciones avanzadas en ingenier\u00eda aeroespacial y administraci\u00f3n de empresas, por lo que es un activo altamente cualificado en seguridad aeron\u00e1utica, cumplimiento y gesti\u00f3n. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"583\" height=\"721\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-CV-Linkedin-2-Kopie.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-CV-Linkedin-2-Kopie.png 583w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-CV-Linkedin-2-Kopie-243x300.png 243w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"4\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Xavier<\/div><div class=\"team_member__description\">Xavier destaca como auditor IOSA y responsable de cumplimiento de seguridad. Con una amplia experiencia en seguridad a\u00e9rea y gesti\u00f3n de crisis, Xavier ha liderado con \u00e9xito numerosas auditor\u00edas globales y programas de seguridad. Entre sus funciones se incluyen la gesti\u00f3n de la planificaci\u00f3n de tripulaciones de cabina de mando y de cabina, as\u00ed como la supervisi\u00f3n de los planes de gesti\u00f3n de crisis, lo que demuestra su experiencia en el cumplimiento operativo y normativo. Xavier ha implantado sistemas de gesti\u00f3n de la calidad y ha formado al personal en protocolos de safety y security. Habla con fluidez varios idiomas y cuenta con numerosas certificaciones, por lo que Xavier es un activo altamente cualificado en seguridad a\u00e9rea, cumplimiento normativo y gesti\u00f3n operativa. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"5\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"466\" height=\"643\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/V-B-1.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/V-B-1.png 466w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/V-B-1-217x300.png 217w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Vlad<\/div><div class=\"team_member__description\">Volodymyr, ciudadano ucraniano, destaca como director de un centro de formaci\u00f3n de vuelo. Con una amplia experiencia en el pilotaje y en la gesti\u00f3n de operaciones de vuelo, Volodymyr ha liderado con \u00e9xito numerosas iniciativas aeron\u00e1uticas. Sus funciones han incluido las de piloto jefe y subdirector de operaciones de vuelo, lo que demuestra su liderazgo en el sector de la aviaci\u00f3n. La carrera de Volodymyr abarca desde instructor PIC hasta profesor asociado en una academia de vuelo. Ha gestionado operaciones a\u00e9reas para las Naciones Unidas y contratos comerciales, haciendo gala de su pericia en la aviaci\u00f3n internacional. Gran conocedor de las normas reglamentarias, Volodymyr es un activo altamente cualificado en la formaci\u00f3n y las operaciones de vuelo. (Freelance)      <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"466\" height=\"643\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/V-B-1.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/V-B-1.png 466w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/V-B-1-217x300.png 217w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"6\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-JM-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-JM-1-1000x1200.png 1000w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-JM-1-249x300.png 249w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Jean-Michel<\/div><div class=\"team_member__description\">Jean-Michel, de Par\u00eds, destaca como Auditor L\u00edder y Auditor de Est\u00e1ndares IOSA. Con una amplia experiencia en operaciones de vuelo y gesti\u00f3n de calidad, Jean-Michel ha dirigido con \u00e9xito numerosas auditor\u00edas de aviaci\u00f3n. Sus funciones incluyen Piloto Jefe para B777 y Asesor del Director de Operaciones de Vuelo, lo que demuestra su experiencia en liderazgo operativo. Jean-Michel tambi\u00e9n ha ocupado los cargos de Jefe del Departamento de Calidad y Oficial de Seguridad de Vuelo, lo que pone de manifiesto su compromiso con la seguridad y el cumplimiento normativo. Fluido en varios idiomas y est\u00e1ndares regulatorios, Jean-Michel es un activo altamente cualificado en seguridad a\u00e9rea y garant\u00eda de calidad. (Freelance)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-JM-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-JM-1-1000x1200.png 1000w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Photo-JM-1-249x300.png 249w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"7\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Jorge-Conti-Website-Pic-Kopie-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Jorge<\/div><div class=\"team_member__description\">Jorge, ciudadano argentino, destaca como auditor IRAM 9001:2015 y director en consultor\u00eda de mantenimiento, calidad y auditor\u00eda. Con m\u00e1s de 35 a\u00f1os de experiencia en la industria de la aviaci\u00f3n, Jorge ha liderado diversas operaciones t\u00e9cnicas. Entre sus funciones se incluyen Jefe de Auditor\u00eda T\u00e9cnica y Coordinador IOSA MNT, lo que demuestra su liderazgo en mantenimiento y cumplimiento normativo. Jorge tambi\u00e9n ha desempe\u00f1ado los cargos de Jefe de Mantenimiento de Simuladores de Vuelo e Ingeniero de Avi\u00f3nica, poniendo de manifiesto su experiencia t\u00e9cnica. Con un s\u00f3lido dominio de las normas regulatorias y la gesti\u00f3n de la calidad, Jorge es un profesional altamente cualificado en seguridad aeron\u00e1utica y auditor\u00eda t\u00e9cnica. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Jorge-Conti-Website-Pic-Kopie-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"8\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/ADRIAN-GONZALEZ-website2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Adrian<\/div><div class=\"team_member__description\">Adrian, de Buenos Aires (Argentina), destaca como Responsable de Calidad Corporativa y auditor IOSA basado en riesgos. Con una amplia experiencia en auditor\u00edas, operaciones de mantenimiento y formaci\u00f3n corporativa, Adrian ha liderado con \u00e9xito diversos proyectos de aviaci\u00f3n. Entre sus funciones se incluyen la implantaci\u00f3n del programa IOSA y el desempe\u00f1o como auditor operativo, lo que demuestra su liderazgo en la gesti\u00f3n de la calidad. Adrian tambi\u00e9n ha sido responsable de la gesti\u00f3n de proyectos de safety, security y calidad, poniendo de manifiesto su experiencia en el cumplimiento normativo. Habla con fluidez varios idiomas y, con s\u00f3lidas competencias en sistemas de calidad, Adrian es un activo de gran valor en los servicios de seguridad operacional y auditor\u00eda en aviaci\u00f3n. \u00a1Y es bastante divertido! (Freelance)      <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/ADRIAN-GONZALEZ-website2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"9\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/WP_20170106_18_24_15_Rich-5-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Jurijs<\/div><div class=\"team_member__description\">Jurijs, de Letonia, destaca como auditor IOSA para operaciones de vuelo. Con una amplia experiencia en seguridad operacional y gesti\u00f3n de la calidad en aviaci\u00f3n, Jurijs ha liderado con \u00e9xito diversas operaciones de aerol\u00edneas. Sus funciones han incluido las de director ejecutivo y gerente responsable, lo que demuestra su pericia en el liderazgo operativo. Jurijs tambi\u00e9n ha trabajado como consultor de operaciones de vuelo y auditor de EU ETS. Con fluidez en varios idiomas y conocimientos t\u00e9cnicos en mantenimiento y ingenier\u00eda aeron\u00e1utica, Jurijs es un activo de gran valor en los servicios de auditor\u00eda y seguridad de la aviaci\u00f3n.    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/WP_20170106_18_24_15_Rich-5-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"10\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/egr-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Phillip<\/div><div class=\"team_member__description\">Phillip Sarkies, ciudadano australiano, destaca como responsable de aseguramiento de la calidad (QA) de la Parte 42 de CASA en Link Airways y como auditor de est\u00e1ndares IOSA. Con una amplia experiencia en revisiones de aeronavegabilidad y gesti\u00f3n de la calidad, Phillip ha liderado con \u00e9xito diversas operaciones de aviaci\u00f3n. Entre sus funciones se incluyen la implantaci\u00f3n del SGC de CAMO en Virgin Australia y la supervisi\u00f3n del cumplimiento normativo como responsable de calidad de la Parte 145. Ha gestionado el desarrollo del SGC para m\u00faltiples organizaciones y ha logrado numerosas certificaciones ISO. Con dominio de la normativa y de los est\u00e1ndares de calidad, Phillip es un profesional altamente cualificado en seguridad aeron\u00e1utica y cumplimiento. (Freelance)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/egr-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"11\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Website-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Stefan<\/div><div class=\"team_member__description\">Stefan, de nacionalidad austriaca, destaca como piloto y experto en aviaci\u00f3n. Con una amplia experiencia en operaciones de vuelo y gesti\u00f3n del tr\u00e1fico a\u00e9reo, Stefan ha desempe\u00f1ado con \u00e9xito diversos cargos en el sector. Su trayectoria incluye puestos de comandante en varias ciudades europeas y de primer oficial s\u00e9nior, lo que demuestra su pericia operativa. Con fluidez en varios idiomas y gran capacidad para la formaci\u00f3n aeron\u00e1utica, Stefan es un activo de gran valor en la industria a\u00e9rea. (Freelancer)    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Website-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"12\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"591\" height=\"647\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Iftikhar-neu.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Iftikhar-neu.png 591w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Iftikhar-neu-274x300.png 274w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Iftikhar<\/div><div class=\"team_member__description\">Iftikhar, ciudadano pakistan\u00ed residente en Suecia, destaca como Ingeniero de Garant\u00eda de Calidad y Auditor de Aviaci\u00f3n. Con 15 a\u00f1os de amplia experiencia en mantenimiento de aeronaves y gesti\u00f3n de calidad, Iftikhar ha liderado diversas operaciones de auditor\u00eda y cumplimiento normativo. Sus funciones incluyen la gesti\u00f3n de garant\u00eda de calidad para entornos CAMO y MRO, as\u00ed como la realizaci\u00f3n de auditor\u00edas para tipos de aeronaves principales como el B737 y el Airbus A320. Iftikhar ha desarrollado e implementado sistemas de gesti\u00f3n de calidad y ha participado en investigaciones de seguridad a\u00e9rea. Con dominio de m\u00faltiples est\u00e1ndares normativos, Iftikhar es un profesional altamente cualificado en seguridad y garant\u00eda de calidad en aviaci\u00f3n. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"591\" height=\"647\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Iftikhar-neu.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Iftikhar-neu.png 591w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Iftikhar-neu-274x300.png 274w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"13\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Matty-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Matthew<\/div><div class=\"team_member__description\">Experto en seguridad operacional e integridad en una importante aerol\u00ednea, con experiencia en cumplimiento normativo, auditor\u00edas de IATA y desarrollo de SMS. Lidera auditor\u00edas de seguridad, evaluaciones de riesgos y formaci\u00f3n, con un enfoque en la aviaci\u00f3n y en est\u00e1ndares intersectoriales. Licenciado en Gesti\u00f3n de la Aviaci\u00f3n, certificado en Just Culture, SMS y auditor\u00eda IOSA. Comprometido con la mejora continua y la excelencia operativa. (Freelance)    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Matty-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"14\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aya-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Aya<\/div><div class=\"team_member__description\">Aigerim (conocida como Aya), de Astan\u00e1, destaca como directora de una ATO, supervisando la formaci\u00f3n de tripulaciones de vuelo con especial \u00e9nfasis en el cumplimiento de las normas de seguridad europeas. Su trayectoria profesional incluye funciones que van desde profesora de ingl\u00e9s hasta instructora jefe de tierra, lo que pone de relieve su competencia en el desarrollo de programas, el cumplimiento normativo y las auditor\u00edas internacionales de seguridad. Con fluidez en ruso, kazajo e ingl\u00e9s, la formaci\u00f3n de Aya se ve enriquecida por una capacitaci\u00f3n especializada en seguridad aeron\u00e1utica y auditor\u00eda, lo que demuestra su destreza en liderazgo y gesti\u00f3n del estr\u00e9s. (Freelancer)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aya-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"15\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/website2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">George<\/div><div class=\"team_member__description\">George, de Chipre, destaca como responsable de Cumplimiento y Seguridad y auditor IOSA. Con m\u00e1s de 40 a\u00f1os de experiencia en aviaci\u00f3n, George ha gestionado con \u00e9xito diversos puestos en operaciones en tierra, seguridad de vuelo y aseguramiento de la calidad. Entre sus cargos se incluyen responsable de Salud y Seguridad, instructor de Seguridad y evaluador de Amenazas, lo que demuestra su experiencia en seguridad operativa y cumplimiento normativo. George ha redactado varios manuales de seguridad y operaciones y ha impartido una amplia formaci\u00f3n a profesionales de la aviaci\u00f3n. Con dominio del ingl\u00e9s y el griego, George es un activo altamente cualificado en seguridad a\u00e9rea, seguridad y cumplimiento normativo y regulatorio. (Freelance)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/website2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"16\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/foto_white-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Marta<\/div><div class=\"team_member__description\">Marta destaca en su papel como Gerente de Comunicaci\u00f3n, transitando sin problemas desde sus inicios profesionales en el an\u00e1lisis de seguridad del tr\u00e1fico a\u00e9reo hasta la orquestaci\u00f3n de estrategias de comunicaci\u00f3n interna. Su trayectoria refleja una profunda adaptabilidad y una habilidad especial para fomentar el compromiso organizacional. Su experiencia, rica en conocimientos sobre factores humanos, marcos legales y gesti\u00f3n de proyectos \u00e1giles, subraya sus innovadoras habilidades para la resoluci\u00f3n de problemas y su destreza en el liderazgo. (Freelance)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/foto_white-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"17\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/02\/photo-freigestellt2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Agnieszka<\/div><div class=\"team_member__description\">Como Vicepresidenta de nuestra sucursal Sp. z o.o., Agnieszka representa a AEROTHRIVE ante nuestros clientes y socios globales en nombre de toda la organizaci\u00f3n.\nAgnieszka aporta una amplia experiencia y conocimientos en gesti\u00f3n de servicios globales, incluida la direcci\u00f3n de equipos de expertos multinacionales. Supervisa proyectos en todas las \u00e1reas de AEROTHRIVE, incluidas operaciones, ventas y atenci\u00f3n al cliente.\nNo dude en ponerse en contacto con Agnieszka para cualquier solicitud o consulta. Puede estar seguro de que ella y su equipo responder\u00e1n de forma r\u00e1pida y profesional, garantizando que se realicen todos los preparativos necesarios.   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/02\/photo-freigestellt2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"18\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"516\" height=\"624\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/wrgwgr.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/wrgwgr.png 516w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/wrgwgr-248x300.png 248w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">St\u00e9phane<\/div><div class=\"team_member__description\">St\u00e9phane destaca como Auditor Jefe RBI de IOSA, habiendo pasado de ser piloto de aviaci\u00f3n rural a experto en operaciones a\u00e9reas. Su adaptabilidad y sus habilidades innovadoras de resoluci\u00f3n de problemas ponen de manifiesto su capacidad de liderazgo. Con funciones en garant\u00eda de calidad y gesti\u00f3n de crisis, su amplia experiencia en aerol\u00edneas subraya su especializaci\u00f3n. Con dominio del ingl\u00e9s y el franc\u00e9s, St\u00e9phane es un activo de primer nivel en seguridad y cumplimiento normativo en aviaci\u00f3n. (Freelancer)    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"516\" height=\"624\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/wrgwgr.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/wrgwgr.png 516w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/wrgwgr-248x300.png 248w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"19\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/P1310331-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Andriy<\/div><div class=\"team_member__description\">Andriy, de Ucrania, es un experimentado Director de Divisi\u00f3n de Ingenier\u00eda y NPH CAMO. Con una amplia experiencia en mantenimiento e ingenier\u00eda de aeronaves, Andriy ha liderado con \u00e9xito diversas operaciones t\u00e9cnicas. Sus funciones incluyen Ingeniero B1 e Ingeniero Principal en aeronaves de producci\u00f3n extranjera, lo que demuestra su experiencia en aeronavegabilidad y cumplimiento normativo. Andriy ha gestionado actividades CAMO y supervisado divisiones de ingenier\u00eda, demostrando su liderazgo en mantenimiento aeron\u00e1utico. Con fluidez en varios idiomas y poseedor de diversas licencias de aeronaves, Andriy es un activo altamente cualificado en seguridad aeron\u00e1utica y gesti\u00f3n de ingenier\u00eda. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/P1310331-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"20\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"585\" height=\"682\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Levent_green_photo.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Levent_green_photo.png 585w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Levent_green_photo-257x300.png 257w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Levent<\/div><div class=\"team_member__description\">Levent, ciudadano turco, destaca como Gerente T\u00e9cnico y de Calidad y Auditor acreditado IOSA RBI. Con m\u00e1s de 30 a\u00f1os de amplia experiencia en aviaci\u00f3n, Levent ha liderado con \u00e9xito programas de cumplimiento, ingenier\u00eda y gesti\u00f3n de la cadena de suministro en aerol\u00edneas, taxis a\u00e9reos y empresas de MRO. Sus cargos incluyen Gerente General, Director T\u00e9cnico, Gerente de Calidad y Seguridad, Gerente de Mantenimiento de L\u00ednea e Instructor para formaciones de auditor\u00eda y calidad. Levent gestion\u00f3 planes de auditor\u00eda de aerol\u00edneas y MRO, programas de cadena de suministro, organizaciones de mantenimiento de l\u00ednea y proporcion\u00f3 servicios de consultor\u00eda y auditor\u00eda a aerol\u00edneas y a la CAA turca. Fluido en ingl\u00e9s y alem\u00e1n y con varias certificaciones, incluyendo formaciones de tipo, Levent es un activo de gran valor en seguridad a\u00e9rea, cumplimiento, mantenimiento y gesti\u00f3n de la cadena de suministro. (Freelance)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"585\" height=\"682\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Levent_green_photo.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Levent_green_photo.png 585w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Levent_green_photo-257x300.png 257w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"21\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Unbenannt-16-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Justine<\/div><div class=\"team_member__description\">\nJustine, de nacionalidad india, es un especialista con amplia experiencia en aviaci\u00f3n y log\u00edstica, con una s\u00f3lida trayectoria en operaciones, formulaci\u00f3n de pol\u00edticas, gesti\u00f3n de partes interesadas y gesti\u00f3n de la seguridad operacional. Gracias a su dilatada experiencia en ADNOC Offshore en los Emiratos \u00c1rabes Unidos y en la Armada de la India, Justine ha gestionado operaciones aeroportuarias, cumplimiento normativo, gesti\u00f3n de crisis y supervisi\u00f3n de proyectos. Su pericia incluye la gesti\u00f3n del tr\u00e1fico a\u00e9reo, la evaluaci\u00f3n de riesgos y el aseguramiento de la calidad. Justine ha contribuido significativamente a la certificaci\u00f3n de aer\u00f3dromos, el apoyo log\u00edstico y el establecimiento de sistemas de gesti\u00f3n de la seguridad operacional (SMS). Con fluidez en ingl\u00e9s y diversas certificaciones, Justine es un activo valioso en la seguridad de la aviaci\u00f3n y la gesti\u00f3n log\u00edstica. (Freelancer)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/Unbenannt-16-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"22\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Dragana-NEW-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Dragana<\/div><div class=\"team_member__description\">Dragana, con m\u00e1s de 30 a\u00f1os en el sector de la aviaci\u00f3n en Serbia, posee un M\u00e1ster en Econom\u00eda y se especializa en seguridad, cumplimiento normativo y auditor\u00edas, especialmente en operaciones a\u00e9reas. Anteriormente jefa de Producto a Bordo y gerente de Acuerdos de Asistencia en Tierra, cuenta con certificaciones en seguridad operacional y protecci\u00f3n de la aviaci\u00f3n, demostrando s\u00f3lidas habilidades comunicativas y organizativas orientadas a la excelencia en la seguridad a\u00e9rea. (Freelance)  <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Dragana-NEW-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"23\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/image00007-Freigestellt-2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">David<\/div><div class=\"team_member__description\">David, director de Garant\u00eda de Calidad\/CM en una aerol\u00ednea l\u00edder en el C\u00e1ucaso desde enero de 2017, ocup\u00f3 anteriormente puestos de auditor\u00eda de calidad y seguridad en otras aerol\u00edneas internacionales. Graduado por la Universidad de Aviaci\u00f3n de Georgia (2006-2009), cuenta con m\u00e1s de una d\u00e9cada de experiencia en cumplimiento y seguridad operacional en aviaci\u00f3n. (Freelancer)  <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/image00007-Freigestellt-2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"24\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1082\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Picture-020224-Website-1000x1082.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Rolands<\/div><div class=\"team_member__description\">Afincado en Letonia, Rolands es un experto en aviaci\u00f3n con amplia experiencia en operaciones de aerol\u00edneas, incluyendo servicios de vuelo, cabina y tierra. Especializado en el cumplimiento de las normativas EASA Air OPS, Part M\/CAMO, Part 145 e IOSA, es experto en auditor\u00eda y seguridad. Como CEO de una aerol\u00ednea letona y director de supervisi\u00f3n del cumplimiento (Compliance Monitoring Manager) de un operador dan\u00e9s, lider\u00f3 los esfuerzos de certificaci\u00f3n AOC. Posee un m\u00e1ster en Econom\u00eda por la Universidad de Letonia y habla con fluidez let\u00f3n, ingl\u00e9s y ruso, adem\u00e1s de tener conocimientos b\u00e1sicos de alem\u00e1n. (Freelancer)    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1082\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Picture-020224-Website-1000x1082.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"25\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Andrii-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Andrii<\/div><div class=\"team_member__description\">Andrii, con m\u00e1s de 20 a\u00f1os en seguridad a\u00e9rea en Ucrania, Hungr\u00eda y los EAU, est\u00e1 especializado en cumplimiento de seguridad, gesti\u00f3n de riesgos e investigaciones de incidentes. Ha sido clave en el inicio de procesos de AOC, ha gestionado el Flight Data Monitoring y los planes de emergencia, y ha auditado m\u00e1s de 100 aeropuertos. Habla con fluidez ingl\u00e9s, ucraniano y ruso, y cuenta con experiencia en gesti\u00f3n de proyectos y antifraude. (Freelancer)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Andrii-1-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"26\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"900\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website.png 3024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-765x1020.png 765w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-225x300.png 225w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-768x1024.png 768w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-1152x1536.png 1152w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-1536x2048.png 1536w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Morten<\/div><div class=\"team_member__description\">De H\u00f8nefoss, Noruega, Morten, experto en seguridad a\u00e9rea, se especializa en SMS, cumplimiento normativo (OACI, EASA, IOSA basada en riesgos), an\u00e1lisis y mitigaci\u00f3n de riesgos. Ha liderado proyectos de seguridad para la UE, STAR Alliance, IATA y OACI, desempe\u00f1ando roles significativos en dos aerol\u00edneas importantes, mejorando la gesti\u00f3n de la seguridad a\u00e9rea y el cumplimiento. <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"900\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website.png 3024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-765x1020.png 765w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-225x300.png 225w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-768x1024.png 768w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-1152x1536.png 1152w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Morten_Website-1536x2048.png 1536w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"27\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"900\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website.png 2582w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-765x1020.png 765w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-225x300.png 225w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-768x1024.png 768w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-1152x1536.png 1152w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-1536x2048.png 1536w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Martin<\/div><div class=\"team_member__description\">Martin, con una trayectoria de 40 a\u00f1os en la aviaci\u00f3n, ha evolucionado desde el dise\u00f1o y el mantenimiento hasta un puesto s\u00e9nior de auditor\u00eda. Desde 2007, ha destacado como auditor, formador y consultor, liderando auditor\u00edas internacionales y especializ\u00e1ndose como MNT y Evaluador de Auditores Jefe. En un operador de jets privados, fue clave en el desarrollo de Sistemas de Gesti\u00f3n Integrados, con \u00e9nfasis en la seguridad a\u00e9rea. Sus funciones como CEO y Responsable de Gesti\u00f3n (Accountable Manager) en diversas empresas ponen de relieve su impacto estrat\u00e9gico en el sector, consolid\u00e1ndolo como un consultor y formador de referencia. (Freelance)    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"900\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website.png 2582w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-765x1020.png 765w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-225x300.png 225w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-768x1024.png 768w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-1152x1536.png 1152w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Martin_Website-1536x2048.png 1536w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"28\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"800\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website.png 4000w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-200x300.png 200w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-683x1024.png 683w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-1024x1536.png 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-1365x2048.png 1365w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Lauris<\/div><div class=\"team_member__description\">Lauris, con m\u00e1s de 20 a\u00f1os en aviaci\u00f3n, ocup\u00f3 puestos clave en aerol\u00edneas europeas, una organizaci\u00f3n de mantenimiento norteamericana y como Responsable de Calidad y Vicepresidente en una aerol\u00ednea letona. Auditor IOSA de IATA, domina el let\u00f3n, el ingl\u00e9s y el ruso, y est\u00e1 especializado en gesti\u00f3n de auditor\u00edas y est\u00e1ndares de seguridad. (Freelance)  <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"800\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website.png 4000w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-200x300.png 200w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-683x1024.png 683w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-1024x1536.png 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Lauris-Website-1365x2048.png 1365w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"29\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"873\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website.png 3575w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-218x300.png 218w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-745x1024.png 745w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-1118x1536.png 1118w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-1491x2048.png 1491w\" sizes=\"auto, (max-width: 873px) 100vw, 873px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Henrik<\/div><div class=\"team_member__description\">Henrik, fundador y CEO de AEROTHRIVE, es un abogado aeron\u00e1utico licenciado en Derecho y certificado en derecho mercantil y corporativo desde 2007. Se especializa en Supervisi\u00f3n del Cumplimiento, Calidad, Gesti\u00f3n de la Seguridad (SMS), Auditor\u00eda Jefe de IOSA y Validaci\u00f3n de Seguridad A\u00e9rea de la UE y el Reino Unido. Realiza auditor\u00edas de certificaci\u00f3n IOSA a nivel mundial, implementa SMS para aerol\u00edneas, imparte conferencias sobre gesti\u00f3n y derecho aeron\u00e1utico, y colabora con la Asociaci\u00f3n Alemana de Derecho de Viajes, destacando la seguridad operacional y el cumplimiento normativo.  <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"873\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website.png 3575w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-218x300.png 218w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-745x1024.png 745w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-1118x1536.png 1118w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/CEO-Henrik-Baark-Website-1491x2048.png 1491w\" sizes=\"auto, (max-width: 873px) 100vw, 873px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"30\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"938\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2.png 2365w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-235x300.png 235w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-801x1024.png 801w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-1201x1536.png 1201w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-1602x2048.png 1602w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Gael<\/div><div class=\"team_member__description\">Ga\u00ebl, un experimentado Auditor L\u00edder IOSA basado en Riesgos, Consultor de Aviaci\u00f3n y Gerente de Formaci\u00f3n, tiene su sede en La Reuni\u00f3n y Par\u00eds. Domina el franc\u00e9s y el ingl\u00e9s, se especializa en cumplimiento normativo, gesti\u00f3n de la seguridad y posee un t\u00edtulo de Ingenier\u00eda de la ENAC. Su experiencia incluye roles en importantes aerol\u00edneas, centr\u00e1ndose en la implementaci\u00f3n de JAR OPS 1, la Monitorizaci\u00f3n de Calidad, Seguridad y Cumplimiento, y la adhesi\u00f3n a los est\u00e1ndares EASA. Ga\u00ebl es tambi\u00e9n Auditor L\u00edder y formador IOSA. (Freelance)    <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"938\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2.png 2365w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-235x300.png 235w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-801x1024.png 801w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-1201x1536.png 1201w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Gael_Website-NEW2-1602x2048.png 1602w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"31\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"947\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW.png 2392w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-237x300.png 237w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-808x1024.png 808w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-1212x1536.png 1212w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-1616x2048.png 1616w\" sizes=\"auto, (max-width: 947px) 100vw, 947px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Roberto<\/div><div class=\"team_member__description\">Roberto, ingeniero civil y piloto comercial de Santiago (Chile), est\u00e1 especializado en aviaci\u00f3n comercial, operaciones en tierra y gesti\u00f3n de proyectos. En una importante aerol\u00ednea, gestion\u00f3 las operaciones del hub, realiz\u00f3 an\u00e1lisis de asistencia en tierra, auditor\u00edas operativas, gesti\u00f3n de SGHA y SLA, y auditor\u00edas t\u00e9cnicas. Cuenta con licencia de piloto con habilitaci\u00f3n IFR y habla espa\u00f1ol, ingl\u00e9s y portugu\u00e9s. (Freelance)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"947\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW.png 2392w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-237x300.png 237w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-808x1024.png 808w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-1212x1536.png 1212w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Roberto_Website-NEW-1616x2048.png 1616w\" sizes=\"auto, (max-width: 947px) 100vw, 947px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"32\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"922\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website.png 3593w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-230x300.png 230w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-787x1024.png 787w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-1180x1536.png 1180w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-1573x2048.png 1573w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Danielle<\/div><div class=\"team_member__description\">Danielle, experta piloto de Windhoek (Namibia) con diez a\u00f1os de experiencia en seguridad y ingenier\u00eda aeron\u00e1utica, ha desempe\u00f1ado cargos relevantes como especialista en seguridad en la Autoridad de Aviaci\u00f3n Civil, mejorando la seguridad y la calidad; subdirectora de seguridad en una escuela de vuelo; e inspectora s\u00e9nior de operaciones de vuelo, centrada en sistemas de seguridad e investigaciones. (Freelance) <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"922\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website.png 3593w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-230x300.png 230w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-787x1024.png 787w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-1180x1536.png 1180w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Danielle_Website-1573x2048.png 1573w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"33\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"800\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website.png 853w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website-200x300.png 200w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website-682x1024.png 682w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Tobias<\/div><div class=\"team_member__description\">Un profesional experimentado de la aviaci\u00f3n de Berl\u00edn, con 3.500 horas de vuelo (3.200 en A320), ha ejercido como Piloto de Seguridad de Vuelo\/Gerente Adjunto de Seguridad desde 2017. Se especializa en Sistemas de Gesti\u00f3n de Seguridad (SMS), cumplimiento normativo, formaci\u00f3n en seguridad, investigaciones, FDM y evaluaci\u00f3n de riesgos. Es experto certificado en SMS y evaluador de riesgos, domina el alem\u00e1n y el ingl\u00e9s, y posee una Licencia de Piloto Comercial con teor\u00eda ATPL. (Freelance)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"800\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website.png 853w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website-200x300.png 200w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Tobias_Westen_Website-682x1024.png 682w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"34\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"900\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website.png 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-765x1020.png 765w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-225x300.png 225w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-768x1024.png 768w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-1152x1536.png 1152w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Per<\/div><div class=\"team_member__description\">Con un t\u00edtulo en Ingenier\u00eda Mec\u00e1nica por una universidad t\u00e9cnica, Per ha destacado en las \u00e1reas de seguridad operacional y cumplimiento en aviaci\u00f3n. Como responsable de Cumplimiento y Seguridad en una aerol\u00ednea sueca, domin\u00f3 marcos regulatorios como el IOSA basado en riesgos y lider\u00f3 amplios programas de formaci\u00f3n para mejorar los est\u00e1ndares del sector. <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"900\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website.png 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-765x1020.png 765w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-225x300.png 225w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-768x1024.png 768w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Per_Website-1152x1536.png 1152w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"35\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW.png 3213w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-250x300.png 250w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-853x1024.png 853w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-1280x1536.png 1280w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-1706x2048.png 1706w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Pawel<\/div><div class=\"team_member__description\">Pawel, auditor IOSA basado en riesgos de Polonia, gestiona el cumplimiento normativo en aviaci\u00f3n, con especializaci\u00f3n en MTO, CAMO, MRO, PO, DO y auditor\u00edas conforme a Part-147, Part-M y FAA, destacando en SMS y legislaci\u00f3n de la UE. Coordina la certificaci\u00f3n Part-21 de EASA y revisa la aeronavegabilidad de ATR 42\/72 y Boeing 737 CL-MAX. Formado en sistemas de aeronaves, seguridad y aspectos legales de las investigaciones de accidentes a\u00e9reos; habla ingl\u00e9s, alem\u00e1n y ruso. (Freelance)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW.png 3213w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-250x300.png 250w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-853x1024.png 853w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-1280x1536.png 1280w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Pawel_Website-NEW-1706x2048.png 1706w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"36\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Kendall-Dorsett-Jr-NEW-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Kendall<\/div><div class=\"team_member__description\">Con sede en Nassau, Bahamas, el Investigador Jefe est\u00e1 especializado en seguridad a\u00e9rea e investigaci\u00f3n de accidentes, con m\u00e1s de diez a\u00f1os de experiencia. Cuenta con un m\u00e1ster en Factores Humanos (Aeroespacial) y certificaciones en pilotaje comercial y control de tr\u00e1fico a\u00e9reo, y lidera investigaciones complejas en la Autoridad de Investigaci\u00f3n de Accidentes de Aeronaves, centradas en la gesti\u00f3n de la seguridad y la respuesta ante emergencias. Su trabajo contribuye de forma significativa a los est\u00e1ndares globales de seguridad de la aviaci\u00f3n. (Freelancer)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Kendall-Dorsett-Jr-NEW-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"37\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Sven-2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Sven<\/div><div class=\"team_member__description\">Sven, con sede en Brandeburgo, Alemania, destaca en la gesti\u00f3n de operaciones de vuelo, desempe\u00f1\u00e1ndose como Persona Designada para Operaciones de Vuelo y Director Responsable Adjunto. Con m\u00e1s de 7 a\u00f1os en Sundair, es piloto t\u00e9cnico con experiencia en operaciones de Airbus A320. Su carrera comenz\u00f3 con mantenimiento en l\u00ednea para A320 y Boeing 737 en Lufthansa Technik, seguido de funciones como Primer Oficial en Aer Lingus y Hamburg Airways. Sven posee habilidades en normativa aeron\u00e1utica, mantenimiento de aeronaves y formaci\u00f3n, con certificaciones de Airbus y Lufthansa Aviation Training Group. Domina el alem\u00e1n y el ingl\u00e9s, y cuenta con habilitaci\u00f3n en competencias aeron\u00e1uticas y certificaci\u00f3n de reuni\u00f3n. (Aut\u00f3nomo)     <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/Sven-2-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div data-item class=\"\"   data-id=\"38\"  >\t\t\t<div data-item-inner><div class=\"slide-item\">    <div class=\"active-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/EBP_8920-short-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div><div class=\"team_member team-description align--left\"><div class=\"team_member__copy\"><div class=\"team_member__title\">Elton<\/div><div class=\"team_member__description\">Elton, responsable de supervisi\u00f3n de seguridad y cumplimiento normativo en Tirana (Albania), con m\u00e1s de cinco a\u00f1os de experiencia, est\u00e1 especializado en la implantaci\u00f3n de SMS y CMS conforme a las normas OACI\/EASA. Con dominio del ingl\u00e9s y el italiano, destaca en cumplimiento normativo, formaci\u00f3n en seguridad, gesti\u00f3n de riesgos y supervisi\u00f3n del rendimiento en seguridad. Titular de una licencia de piloto privado, su trayectoria en gesti\u00f3n aeron\u00e1utica subraya su compromiso con la seguridad de la aviaci\u00f3n. (Freelancer)   <\/div><\/div><\/div>        <\/div>    <\/div>    <div class=\"inactive-content\">        <div class=\"content-wrapper\"><div class=\"team_member team-portrait align--left\"><div class=\"team_member__image\"><figure class=\"f4_img-container  portrait\" ><img width=\"1000\" height=\"1200\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/EBP_8920-short-1000x1200.png\" class=\"attachment-team-portrait size-team-portrait\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/figure><\/div><\/div>        <\/div>    <\/div><\/div>\t\t\t<\/div>\t\t<\/div>        <\/div>    <\/div><\/div><div data-ui><div data-navigation>    <div data-btn-prev><\/div>    <div data-btn-next><\/div><\/div><ul data-bullets><\/ul><div data-pagination><\/div>    <\/div><\/div>    <\/div>\n\n<\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--medium);padding-bottom:var(--wp--preset--spacing--medium)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Somos inspiradores, ejecutores y entusiastas.<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>AEROTHRIVE aspira a ser un l\u00edder del sector y se prev\u00e9 que se inscriba\/ acredite en los principales programas de auditor\u00eda, adem\u00e1s de contar con un amplio programa de formaci\u00f3n p\u00fablica con bases de formaci\u00f3n en Europa, Oriente Medio, Asia Oriental y las Am\u00e9ricas. La formaci\u00f3n interna y la consultor\u00eda complementan el porfolio. <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-ab785429 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--default);padding-bottom:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"is-style-h5\">INDEPENDIENTE<\/p>\n\n\n\n<p class=\"is-style-default\">Libre de cualquier grupo de aerol\u00edneas, AEROTHRIVE ofrece servicios honestos, justos y directos, sin sesgos del propietario ni burocracia corporativa.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"is-style-h5\">CALIDAD ALEMANA<\/p>\n\n\n\n<p>Ll\u00e1melo neur\u00f3tico, gen\u00e9tico o simplemente alem\u00e1n: estamos totalmente comprometidos con ofrecer un servicio fiable junto con nuestro equipo de expertos globales multinacionales de todo el mundo.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"is-style-h5\">PROXIMIDAD GLOBAL<\/p>\n\n\n\n<p>Contamos con una red consolidada de los mejores expertos, que combina de forma \u00fanica la promesa de calidad alemana con una \u201cexperiencia local global\u201d.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div  class=\" f4-block-logo-grid alignfull\"   >\n    <div class=\"block-media\">\n        <div class=\"f4_img--adaptive hero-image\" ><div class=\"f4_img-container f4_img--mobile portrait\" ><img width=\"717\" height=\"1024\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/partner-image-scaled-1-e1710765267870-717x1024.jpg\" class=\"attachment-large size-large\" alt=\"Empowering aviation professionals worldwide through cutting-edge training, advisory, and auditing services\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/partner-image-scaled-1-e1710765267870-717x1024.jpg 717w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/partner-image-scaled-1-e1710765267870-210x300.jpg 210w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/partner-image-scaled-1-e1710765267870-1075x1536.jpg 1075w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/partner-image-scaled-1-e1710765267870.jpg 1194w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/div><div class=\"f4_img-container f4_img--desktop landscape\" ><img width=\"3840\" height=\"2560\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/partner-image-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Achieve the highest-tier Professional Diploma\u2014AEROTHRIVE Excellence Diplomas\u2014by mastering multiple training courses. Discover eligible combinations!\" decoding=\"async\" loading=\"lazy\" \/><\/div><\/div>    <\/div>\n    <div class=\"block-content\">\n    <div class=\"acf-innerblocks-container\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9216ddd0 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--default)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Socios y Clientes<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Colaborando estrechamente con los l\u00edderes del sector: Nuestros socios globales abarcan desde reconocidos grupos a\u00e9reos hasta actores clave en diversos segmentos de la aviaci\u00f3n, incluyendo empresas de software y proveedores de datos e inteligencia.<\/p>\n<\/div>\n<\/div>\n\n<\/div>    <\/div>\n    <div class=\"block-logos\">\n            <div class=\"f4_slider swiper logo-grid-slider\" id=\"flow4_slider_6a983744a230d\" data-options=\"{&quot;speed&quot;:2000,&quot;scrollbar&quot;:false,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;slidesPerView&quot;:&quot;auto&quot;,&quot;loop&quot;:true,&quot;loopAddBlankSlides&quot;:true,&quot;autoplay&quot;:{&quot;delay&quot;:0,&quot;pauseOnMouseEnter&quot;:true,&quot;disableOnInteraction&quot;:false},&quot;mousewheel&quot;:false,&quot;thumbs&quot;:null}\"> <div class=\"swiper-wrapper\">\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.flygbra.se\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/idAnADBQbP.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/amapola.nu\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/amapola.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/sundair.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/05\/jhgjhgf.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.riyadhair.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/RX.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.vivaaerobus.com\/en-us\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/viv.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.lufthansa.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/LH_neu.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.allegiantair.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/allegiant.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.koreanair.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/Koreannew.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.hamburg-airport.de\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/Unbenannt-1.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.tui.com\/service-kontakt\/flug\/tuifly\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/07\/unnamed-2.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"http:\/\/airfrance.fr\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/AF.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.boeing.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Boeing.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.flyasky.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/06\/fvawv.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flynorse.com\/en-US?gad_source=1&#038;gclid=Cj0KCQiAi_G5BhDXARIsAN5SX7rFEsI2Anp5ylY6a5pMBylgPnTAgoydL9iIXVneCyQllsSJ4NitVc4aAlVKEALw_wcB&#038;gclsrc=aw.ds\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/11\/Norse.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.lufthansa-city.com\/en\/home.html\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/12\/City.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/aviasg.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/Logo_ASG-scaled.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/interreg-baltic.eu\/project\/bsr-hyairport\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/HyAirport.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/psaa.com.sa\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/PSAA-weiss-e1706808822483.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.jet2.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/11\/Jet2.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.condor.com\/eu\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/02\/photo-Kopie-scaled.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.atc-md.aero\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/11\/ATC.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/urga.com.ua\/en\/o-kompanii\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/11\/URG.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/ewa-air.com\/en\/index.html\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/11\/ewa.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.volotea.com\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/11\/volotea.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.sarp.org\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/logo-sarpcheck.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.aeromexico.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/12\/AM.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.hahnair.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/12\/hahnair.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.helvetic.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/12\/helvetic.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flyunitednigeria.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/UnmitedLogo.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.airhaifa.com\/about-he\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/images-8.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flymarabu.com\/en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/Marabu.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flyarystan.com\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/Arystan.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/airastana.com\/global-en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/Astana.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/jettime.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/Jettime.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.aviaam.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/Logo_AviaM.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_Qazaq.jpg\" alt=\"\"><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.leav.com\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/LEAV.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.air.bg\/en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/Bulgaria.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flyvaluejet.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/ValueJet-logo.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.alpes-helico.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/logo_AlpesHelicopteres.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.finnair.com\/us-en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/Finnair-Kopie.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/emirates.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/Emirates.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.israirairlines.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/images-9.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.airarabia.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/AirArabia.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.saudia.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Saudia.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/getjet.aero\/?gad_source=1&#038;gad_campaignid=21367489380&#038;gbraid=0AAAAA93AUfhNFo6NVffqI0e9kS1Hvl_R2&#038;gclid=Cj0KCQjwjdTCBhCLARIsAEu8bpJfqRrwoYtWnoK7PTDN5f2C3zW-OLJA9S4UnNpv4HIqS3nEff36iusaAlbyEALw_wcB\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/03\/getjet.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/ifly.gr\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/04\/iFly.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.atlasair.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/AtlasAir.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/airintersalonica.gr\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/04\/Intersalonika.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.dhl.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/01\/DHL.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.arikair.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/ArikAir.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.superior-air.gr\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/04\/Superior.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.sunexpress.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Sun-Express.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.flycycladic.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/04\/Cycladic.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.airsial.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/AirSial.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flyhoper.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/Logo_hoper.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.flylili.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/logo-FlyLili.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"http:\/\/www.esperia-aviation.it\/en\/homepage-en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/logo_Esperia.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/airexplore.aero\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/05\/Logo_AirExplore-2-scaled.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/bbnairlines.id\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/BBN-Indonesia.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/bellavia.gr\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/06\/BELLAVIA-LOGO-FINAL.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flyairpeace.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/AirPeace.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/fly4less.hu\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/06\/FLY-logo-1.png\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/airraro.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/RAR.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.kamair.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Kam-Air.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.cyprusairways.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Cyprus.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/westatlantic.eu\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/West-Atlantic.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.dhl.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/EAT.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.flyslm.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/SLM.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.aeromexico.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/AeromexicoConnect.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/albatechnics.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/ALBA.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/kasaskenya.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/KASAS.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.gulfair.com\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/GulfAir.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/dk.sunclassairlines.dk\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Sunclass.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/flypivot.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Pivot.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.airnostrum.es\/en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Air-Nostrum.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.aerolineas.com.ar\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/08\/Aerolineas.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.flybird.aero\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/Logo_FlyBird.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.sanad.ae\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_Sanad.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.huairlines.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_hungary.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/vietjetqazaqstan.kz\/en?locale=en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_Vietjet.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.casas.sr\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/Logo_CASAS.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.heli-flight.de\/en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_heliflight.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.aircorporate.it\/?lang=en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_AirCorporate.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/ciocco.it\/en\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/logo_ilciocco.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.gaa.aero\/en\/gaa\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/Logo_GAA.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.titan-airways.com\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/Logo_Titan.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.lgs.lv\/en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/Logo_LGS.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div>\t\t<div class=\"swiper-slide \"   >\t\t\t<div class=\"swiper-slide__inner\"><div class=\"logo-item\"><a href=\"https:\/\/www.atlanticairways.com\/en\/\" target=\"_blank\" title=\"\"><img decoding=\"async\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2025\/12\/atlantic.jpg\" alt=\"\"><\/a><\/div>\t\t\t<\/div>\t\t<\/div><\/div><\/div>    <\/div>\n<\/div>\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-top:var(--wp--preset--spacing--medium);margin-bottom:var(--wp--preset--spacing--medium);padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Su vecino global.<br\/>Cont\u00e1ctenos en todo el mundo.<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Nuestros cursos de formaci\u00f3n y servicios de auditor\u00eda y consultor\u00eda a nivel mundial abarcan todas las zonas horarias del planeta. Con sede central en el coraz\u00f3n de Europa, tambi\u00e9n ofrecemos asistencia localizada a trav\u00e9s de nuestras bases regionales, cada una con sus propios contactos dedicados. <\/p>\n<\/div>\n<\/div>\n\n\n\n<div  class=\" f4-block-image-with-cards cards-4\"   >\n    <div class=\"f4_img--adaptive card-image\" ><div class=\"f4_img-container f4_img--mobile landscape\" ><img width=\"1524\" height=\"762\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map.png\" class=\"attachment-16-to-9 size-16-to-9\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map.png 1524w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map-300x150.png 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map-1024x512.png 1024w\" sizes=\"auto, (max-width: 1524px) 100vw, 1524px\" \/><\/div><div class=\"f4_img-container f4_img--desktop landscape\" ><img width=\"1524\" height=\"762\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map.png\" class=\"attachment-16-to-9 size-16-to-9\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map.png 1524w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map-300x150.png 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/02\/aerothrive-map-1024x512.png 1024w\" sizes=\"auto, (max-width: 1524px) 100vw, 1524px\" \/><\/div><\/div><div class=\"cards-wrapper\"><div class=\"single-card\"><h3 class=\"hero-card-headline is-style-h4\">Las Am\u00e9ricas<\/h3><div class=\"hero-card-text\"><p>Miami, hora est\u00e1ndar del Este (EST)<br \/>\ny hora de verano del Este (EDT)<\/p>\n<p>Correo electr\u00f3nico:<br \/>\n<a href=\"mailto:Americas@AEROTHRIVE.com\">Americas@AEROTHRIVE.com<\/a><\/p>\n<p>Tel\u00e9fono:<br \/>\n<span>+49 156 79267670<\/span><span><\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" target=\"\" href=\"https:\/\/aerothrive.com\/contact\/\">Contacto<\/a><\/div><\/div><\/div><div class=\"single-card\"><h3 class=\"hero-card-headline is-style-h4\">Europa, \u00c1frica<\/h3><div class=\"hero-card-text\"><p>Hamburgo, hora central europea (CET)<br \/>\ny hora de verano de Europa Central (CEST)<\/p>\n<p>Correo electr\u00f3nico:<br \/>\n<a href=\"mailto:hello@AEROTHRIVE.com\">hello@AEROTHRIVE.com<\/a><\/p>\n<p>Tel\u00e9fono:<br \/>\n<span>+49 156 79267670<\/span><span><\/span><\/p>\n<\/div><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" target=\"\" href=\"https:\/\/aerothrive.com\/contact\/\">Contacto<\/a><\/div><\/div><\/div><div class=\"single-card\"><h3 class=\"hero-card-headline is-style-h4\">Oriente Medio<\/h3><div class=\"hero-card-text\"><p>Dub\u00e1i,<br \/>\nhora est\u00e1ndar del Golfo (GST)<\/p>\n<p>Correo electr\u00f3nico:<br \/>\n<a href=\"mailto:AfricaMidEast@AEROTHRIVE.com\">AfricaMidEast@AEROTHRIVE.com<\/a><\/p>\n<p>Tel\u00e9fono:<br \/>\n<span>+49 156 79267670<\/span><span><\/span><\/p>\n<\/div><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" target=\"\" href=\"https:\/\/aerothrive.com\/contact\/\">Contacto<\/a><\/div><\/div><\/div><div class=\"single-card\"><h3 class=\"hero-card-headline is-style-h4\">Australia, Lejano Oriente, Pac\u00edfico<\/h3><div class=\"hero-card-text\"><p>Hong Kong,<br \/>\nhora de Hong Kong (HKT)<\/p>\n<p>Correo electr\u00f3nico:<br \/>\n<a href=\"mailto:AustraliaFarEast@AEROTHRIVE.com\">AustraliaFarEast@AEROTHRIVE.com<\/a><\/p>\n<p>Tel\u00e9fono:<br \/>\n<span>+49 156 79267670<\/span><span><\/span><\/p>\n<\/div><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" target=\"\" href=\"https:\/\/aerothrive.com\/contact\/\">Contacto<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n<div  class=\" f4-block-newsletter is-layout-constrained alignfull\"   >\n    <div class=\"block-media\">\n        <div class=\"f4_img--adaptive hero-image\" ><div class=\"f4_img-container f4_img--mobile landscape\" ><img width=\"1024\" height=\"278\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-1024x278.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-1024x278.jpg 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-300x81.jpg 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-1536x417.jpg 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"f4_img-container f4_img--desktop landscape\" ><img width=\"1920\" height=\"521\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air.jpg 1920w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-300x81.jpg 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-1024x278.jpg 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/09\/airplane_air-1536x417.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div>    <\/div>\n    <div class=\"block-inner\">\n        <div class=\"block-content\">\n            <div class=\"acf-innerblocks-container\">\n\n<h2 class=\"wp-block-heading\">Bolet\u00edn<\/h2>\n\n\n\n<p>Aseg\u00farese de mantenerse siempre al d\u00eda de las \u00faltimas novedades de <strong>AERO<\/strong>THRIVE sobre temas y soluciones de seguridad de vuelo.<\/p>\n\n<\/div>                    <script type=\"text\/javascript\">\n                        var onloadSibCallback = function () {\n                            jQuery('.g-recaptcha').each(function (index, el) {\n                                grecaptcha.render(el, {\n                                    'sitekey': jQuery(el).attr('data-sitekey')\n                                });\n                            });\n                        };\n                    <\/script>\n\t\t\t\t\t                <script src=\"https:\/\/www.google.com\/recaptcha\/api.js?onload=onloadSibCallback&#038;render=explicit\" async defer><\/script>\n\t\t\t\t\n\t\t\t<form id=\"sib_signup_form_2\" method=\"post\" class=\"sib_signup_form\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img\n\t\t\t\t\t\t\tsrc=\"https:\/\/aerothrive.com\/wp-includes\/images\/spinner.gif\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"2\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Please fill out this field\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Your email address is invalid\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"760ab6ba1f\">\n\t\t\t\t<div class=\"sib_signup_box_inside_2\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                    \t\t\t\t\t<p class=\"sib-email-area\">\r\n    Email Address*\r\n    <input type=\"email\" class=\"sib-email-area\" name=\"email\" required=\"required\">\r\n<\/p>\r\n<p class=\"sib-NAME-area\">\r\n    Name\r\n    <input type=\"text\" class=\"sib-NAME-area\" name=\"NAME\">\r\n<\/p>\r\n<p class=\"sib-CHECKBOX-area\">\r\n<input type=\"checkbox\" name=\"terms\" required=\"required\"><label>I consent to the processing of my personal data. I have read and consent to the <a target=\"_blank\" href=\"https:\/\/aerothrive.com\/privacy-policy\/\">privacy policy<\/a>.<\/label>\r\n<\/p>\r\n<p>\r\n<div id=\"sib_captcha\" class=\"g-recaptcha\" data-sitekey=\"6Lc51a8pAAAAALe28x8UHaWGBpmOdcIQ4muXwU1f\"><\/div>\r\n<\/p>\r\n<p>\r\n    <input type=\"submit\" class=\"sib-default-btn\" value=\"Subscribe\">\r\n<\/p>\r\n\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_2 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_2 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_2 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_2 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t        <\/div>\n    <\/div>\n<\/div>\n\n<div  class=\" f4-block-linkedin-newsletter alignwide\"   >\n    <div class=\"block-inner\">\n        <div class=\"block-content\">\n                    <\/div>\n\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Acelerando la aviaci\u00f3n. Airbourne en Alemania. Nuestro equipo, rico en experiencia y rebosante de entusiasmo, no es solo un grupo de profesionales: somos aut\u00e9nticos Aviationeers. Con nuestra amplia experiencia pr\u00e1ctica, acumulada durante varias d\u00e9cadas, nos especializamos en guiarle en cada fase de su trayectoria en la aviaci\u00f3n. Perm\u00edtanos conducirle hacia la experiencia de vuelo fluida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-39239","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sobre nosotros | AEROTHRIVE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aerothrive.com\/es\/sobre-nosotros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre nosotros | AEROTHRIVE\" \/>\n<meta property=\"og:description\" content=\"Acelerando la aviaci\u00f3n. Airbourne en Alemania. Nuestro equipo, rico en experiencia y rebosante de entusiasmo, no es solo un grupo de profesionales: somos aut\u00e9nticos Aviationeers. Con nuestra amplia experiencia pr\u00e1ctica, acumulada durante varias d\u00e9cadas, nos especializamos en guiarle en cada fase de su trayectoria en la aviaci\u00f3n. Perm\u00edtanos conducirle hacia la experiencia de vuelo fluida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aerothrive.com\/es\/sobre-nosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"AEROTHRIVE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T15:16:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/\",\"name\":\"Sobre nosotros | AEROTHRIVE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/wefsd-1024x575.jpg\",\"datePublished\":\"2024-01-23T09:31:42+00:00\",\"dateModified\":\"2026-05-06T15:16:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/wefsd-1024x575.jpg\",\"contentUrl\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/wefsd-1024x575.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/sobre-nosotros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre nosotros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/\",\"name\":\"AEROTHRIVE\",\"description\":\"Global Aviation Excellence\",\"publisher\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#organization\"},\"alternateName\":\"AEROTHRIVE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#organization\",\"name\":\"AEROTHRIVE GmbH\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/aerothrive-logo.png\",\"contentUrl\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/aerothrive-logo.png\",\"width\":3508,\"height\":2480,\"caption\":\"AEROTHRIVE GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre nosotros | AEROTHRIVE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/","og_locale":"es_ES","og_type":"article","og_title":"Sobre nosotros | AEROTHRIVE","og_description":"Acelerando la aviaci\u00f3n. Airbourne en Alemania. Nuestro equipo, rico en experiencia y rebosante de entusiasmo, no es solo un grupo de profesionales: somos aut\u00e9nticos Aviationeers. Con nuestra amplia experiencia pr\u00e1ctica, acumulada durante varias d\u00e9cadas, nos especializamos en guiarle en cada fase de su trayectoria en la aviaci\u00f3n. Perm\u00edtanos conducirle hacia la experiencia de vuelo fluida [&hellip;]","og_url":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/","og_site_name":"AEROTHRIVE","article_modified_time":"2026-05-06T15:16:15+00:00","og_image":[{"width":2560,"height":1437,"url":"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/","url":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/","name":"Sobre nosotros | AEROTHRIVE","isPartOf":{"@id":"https:\/\/aerothrive.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/#primaryimage"},"image":{"@id":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/#primaryimage"},"thumbnailUrl":"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1024x575.jpg","datePublished":"2024-01-23T09:31:42+00:00","dateModified":"2026-05-06T15:16:15+00:00","breadcrumb":{"@id":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aerothrive.com\/es\/sobre-nosotros\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/#primaryimage","url":"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1024x575.jpg","contentUrl":"https:\/\/aerothrive.com\/wp-content\/uploads\/2026\/01\/wefsd-1024x575.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/aerothrive.com\/es\/sobre-nosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aerothrive.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sobre nosotros"}]},{"@type":"WebSite","@id":"https:\/\/aerothrive.com\/es\/#website","url":"https:\/\/aerothrive.com\/es\/","name":"AEROTHRIVE","description":"Global Aviation Excellence","publisher":{"@id":"https:\/\/aerothrive.com\/es\/#organization"},"alternateName":"AEROTHRIVE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aerothrive.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/aerothrive.com\/es\/#organization","name":"AEROTHRIVE GmbH","url":"https:\/\/aerothrive.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/aerothrive.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/aerothrive-logo.png","contentUrl":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/aerothrive-logo.png","width":3508,"height":2480,"caption":"AEROTHRIVE GmbH"},"image":{"@id":"https:\/\/aerothrive.com\/es\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/pages\/39239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/comments?post=39239"}],"version-history":[{"count":2,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/pages\/39239\/revisions"}],"predecessor-version":[{"id":39246,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/pages\/39239\/revisions\/39246"}],"wp:attachment":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/media?parent=39239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}