{"id":38959,"date":"2023-11-08T16:56:23","date_gmt":"2023-11-08T15:56:23","guid":{"rendered":"https:\/\/stage.aerothrive.com\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/"},"modified":"2026-05-06T15:46:12","modified_gmt":"2026-05-06T13:46:12","slug":"diploma-de-experto-en-gestion-de-seguridad-parte-145","status":"publish","type":"f4_diploma","link":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/","title":{"rendered":"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading is-style-h3\">Profesionales del cumplimiento normativo que dominan las principales competencias en auditor\u00eda pr\u00e1ctica y sistemas de gesti\u00f3n.<\/h2>\n\n\n\n<p>Completar con \u00e9xito determinadas combinaciones de cursos de formaci\u00f3n de AEROTHRIVE no solo le otorga certificados, sino que tambi\u00e9n le cualifica para obtener un diploma adicional de forma gratuita. Este diploma es un testimonio de su trayectoria de desarrollo profesional, \u00a1mostrando sus logros al mundo!  <\/p>\n\n\n\n<p>Eleve su perfil profesional con los diplomas de gesti\u00f3n aeron\u00e1utica de AEROTHRIVE. Complete con \u00e9xito las formaciones que se muestran a continuaci\u00f3n y obtenga este reconocible certificado de diploma, demostrando su experiencia en el sector aeron\u00e1utico ante socios, colegas y posibles empleadores. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"817\" height=\"1024\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Promo_Pic_of_Certs_Diploma-817x1024.png\" alt=\"\" class=\"wp-image-850\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Promo_Pic_of_Certs_Diploma-817x1024.png 817w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Promo_Pic_of_Certs_Diploma-239x300.png 239w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Promo_Pic_of_Certs_Diploma-1226x1536.png 1226w, https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/Promo_Pic_of_Certs_Diploma.png 1596w\" sizes=\"auto, (max-width: 817px) 100vw, 817px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--default);padding-bottom:var(--wp--preset--spacing--default)\">\n<h2 class=\"wp-block-heading is-style-decor-element\">Domine estos cursos para obtener el Diploma:<\/h2>\n\n\n\n<div  class=\" f4-block-training-teaser-grid\"   >\n\n\t\n\t<div id=\"training-teaser-grid_6a983de7e72ab\"  class=\"f4_post-teaser-group f4_post-teaser-group--default  f4_post-teaser-group--training\"  data-query=\"{&quot;lang&quot;:&quot;es&quot;,&quot;paged&quot;:1,&quot;posts_per_page&quot;:&quot;3&quot;,&quot;found_posts&quot;:32,&quot;max_num_pages&quot;:11,&quot;query_args&quot;:{&quot;post_status&quot;:&quot;publish&quot;,&quot;post_type&quot;:[&quot;f4_training&quot;],&quot;posts_per_page&quot;:&quot;3&quot;,&quot;paged&quot;:1,&quot;ignore_sticky_posts&quot;:true,&quot;has_password&quot;:false,&quot;post__not_in&quot;:[],&quot;post__in&quot;:null,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;fields&quot;:&quot;all&quot;},&quot;group_id&quot;:&quot;training-teaser-grid_6a983de7e72ab&quot;,&quot;layout&quot;:null,&quot;defaultTeaserClass&quot;:&quot;PostTeaserTraining01&quot;,&quot;injectedTeasers&quot;:null}\"><nav data-nav><ul data-list><li data-item class=\" \"><article  class=\"f4_post-teaser post-teaser--training-01   has-image\"  id=\"post-38924\"  data-group-id=\"training-teaser-grid_6a983de7e72ab\" ><div class=\"f4_post-teaser__inner\"><div class=\"f4_post-teaser__meta\"><div class=\"post-term-list f4_tax_category\"><div class=\"post-taxonomy-name\">Category:<\/div><ul><li>Legal<\/li><\/ul><\/div><div class=\"post-term-list f4_tax_industry\"><div class=\"post-taxonomy-name\">Industry:<\/div><ul><li>Aerol\u00edneas<\/li><li>MRO<\/li><li>Autoridades y organizaciones<\/li><\/ul><\/div><\/div><a class=\"f4_post-teaser__teaser-image \"  href=\"https:\/\/aerothrive.com\/es\/training\/easa-part-145-2-dias\/\"  target=\"_self\"  aria-label=\"EASA Parte 145 (2 d\u00edas)\" ><img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"299\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-532x299.jpg\" class=\"attachment-16-to-9-small size-16-to-9-small wp-post-image\" alt=\"\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-532x299.jpg 532w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-300x168.jpg 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-1024x574.jpg 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-1536x861.jpg 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-2048x1148.jpg 2048w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-528x297.jpg 528w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/12\/Part145-1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/a><div class=\"f4_post-teaser__header\"><div class=\"f4_post-teaser__title \" ><span class=\"training-title\">EASA Parte 145 (2 d\u00edas)<\/span><\/div><div class=\"f4_post-teaser__subtitle \" >El concepto, los contenidos y la aplicaci\u00f3n del marco legal EASA Parte 145. N\u00famero de curso: AT013. En caso de que no se muestre ninguna fecha de formaci\u00f3n p\u00fablica, o si dispone de un grupo de participantes m\u00e1s numeroso para formar, p\u00f3ngase en contacto con sales@AEROTHRIVE.com y reciba su oferta de formaci\u00f3n personalizada. Seg\u00fan el n\u00famero de participantes, las tarifas por asistente pueden reducirse considerablemente.<\/div><\/div><div class=\"f4_post-teaser__content \" >\t<div class=\"training-goal\"><strong>Cours Goals<\/strong><br>Los participantes estar\u00e1n cualificados para comprender el origen, el concepto, el mecanismo y determinados detalles del marco regulatorio EASA Parte 145 y su aplicaci\u00f3n en la industria.\t<\/div>\t<div class=\"training-takeaways\"><strong>Your takeaways <\/strong><br><ul><li>Obtendr\u00e1 la capacidad de comprender la estructura de las normas relacionadas con EASA Parte 145 y de navegar por ellas.<\/li><li>Adquirir\u00e1 la capacidad de evaluar adecuadamente la intenci\u00f3n y la aplicabilidad de los requisitos de EASA Parte 145.<\/li><li>Se familiarizar\u00e1 con la utilizaci\u00f3n de las normas EASA Part 145 en su trabajo diario.<\/li><\/ul>\t<\/div><\/div><div class=\"f4_post-teaser__footer \" ><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/aerothrive.com\/es\/training\/easa-part-145-2-dias\/\">Details and booking<\/a><\/div><\/div><\/div><\/div><\/article><\/li><li data-item class=\" \"><article  class=\"f4_post-teaser post-teaser--training-01   has-image\"  id=\"post-38936\"  data-group-id=\"training-teaser-grid_6a983de7e72ab\" ><div class=\"f4_post-teaser__inner\"><div class=\"f4_post-teaser__meta\"><div class=\"post-term-list f4_tax_category\"><div class=\"post-taxonomy-name\">Category:<\/div><ul><li>Seguridad<\/li><\/ul><\/div><div class=\"post-term-list f4_tax_industry\"><div class=\"post-taxonomy-name\">Industry: <\/div><ul><\/li>All<\/li><\/ul><\/div><\/div><a class=\"f4_post-teaser__teaser-image \"  href=\"https:\/\/aerothrive.com\/es\/training\/sistemas-de-gestion-de-la-seguridad-operacional-premium-5-dias\/\"  target=\"_self\"  aria-label=\"Sistemas de Gesti\u00f3n de la Seguridad Operacional, Premium (5 d\u00edas)\" ><img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"299\" src=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-532x299.jpg\" class=\"attachment-16-to-9-small size-16-to-9-small wp-post-image\" alt=\"\" srcset=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-532x299.jpg 532w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-300x168.jpg 300w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-1024x573.jpg 1024w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-1536x859.jpg 1536w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-528x297.jpg 528w, https:\/\/aerothrive.com\/wp-content\/uploads\/2023\/10\/Risks-1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/a><div class=\"f4_post-teaser__header\"><div class=\"f4_post-teaser__title \" ><span class=\"training-title\">Sistemas de Gesti\u00f3n de la Seguridad Operacional, Premium (5 d\u00edas)<\/span><\/div><div class=\"f4_post-teaser__subtitle \" >De expertos l\u00edderes en el \u00e1rea de sistemas de gesti\u00f3n de la seguridad operacional. N\u00famero de curso: AT006a. En caso de que no se muestre ninguna fecha de formaci\u00f3n p\u00fablica, o si dispone de un grupo de participantes m\u00e1s numeroso para formar, p\u00f3ngase en contacto con sales@AEROTHRIVE.com y reciba su oferta de formaci\u00f3n personalizada. Seg\u00fan el n\u00famero de participantes, las tarifas por asistente pueden reducirse considerablemente.<\/div><\/div><div class=\"f4_post-teaser__content \" >\t<div class=\"training-goal\"><strong>Cours Goals<\/strong><br>Nuestro curso insignia de SMS permite a los participantes elevar las actividades bajo SMS desde un cumplimiento posiblemente menos efectivo de requisitos externos hacia una mejora verdaderamente valiosa de las actividades empresariales de su compa\u00f1\u00eda.\t<\/div>\t<div class=\"training-takeaways\"><strong>Your takeaways <\/strong><br><ul><li>Soluciones pr\u00e1cticas para gestionar sus tareas diarias de la forma m\u00e1s eficiente y eficaz.<\/li><li>Inspiraci\u00f3n mediante el intercambio con compa\u00f1eros de formaci\u00f3n altamente especializados.<\/li><li>Elegibilidad del certificado obtenido para certificados de diploma AEROTHRIVE adicionales gratuitos (se aplican t\u00e9rminos y condiciones).<\/li><\/ul>\t<\/div><\/div><div class=\"f4_post-teaser__footer \" ><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div class=\"wp-block-button is-style-text has-icon--circle-outline-arrow-right--primary icon-position--left\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/aerothrive.com\/es\/training\/sistemas-de-gestion-de-la-seguridad-operacional-premium-5-dias\/\">Details and booking<\/a><\/div><\/div><\/div><\/div><\/article><\/li><\/ul><\/nav><\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Profesionales del cumplimiento normativo que dominan las principales competencias en auditor\u00eda pr\u00e1ctica y sistemas de gesti\u00f3n.<\/p>\n","protected":false},"featured_media":38960,"template":"","f4_tax_type":[121],"f4_tax_category":[113,114],"f4_tax_industry":[109,110,111],"class_list":["post-38959","f4_diploma","type-f4_diploma","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145 | AEROTHRIVE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145 | AEROTHRIVE\" \/>\n<meta property=\"og:description\" content=\"Profesionales del cumplimiento normativo que dominan las principales competencias en auditor\u00eda pr\u00e1ctica y sistemas de gesti\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/\" \/>\n<meta property=\"og:site_name\" content=\"AEROTHRIVE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T13:46:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/IMG_5013-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/\",\"name\":\"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145 | AEROTHRIVE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_5013-scaled.jpg\",\"datePublished\":\"2023-11-08T15:56:23+00:00\",\"dateModified\":\"2026-05-06T13:46:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_5013-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_5013-scaled.jpg\",\"width\":2560,\"height\":1470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/diploma\\\/diploma-de-experto-en-gestion-de-seguridad-parte-145\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/\",\"name\":\"AEROTHRIVE\",\"description\":\"Global Aviation Excellence\",\"publisher\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#organization\"},\"alternateName\":\"AEROTHRIVE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#organization\",\"name\":\"AEROTHRIVE GmbH\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/aerothrive-logo.png\",\"contentUrl\":\"https:\\\/\\\/aerothrive.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/aerothrive-logo.png\",\"width\":3508,\"height\":2480,\"caption\":\"AEROTHRIVE GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/aerothrive.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145 | AEROTHRIVE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/","og_locale":"es_ES","og_type":"article","og_title":"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145 | AEROTHRIVE","og_description":"Profesionales del cumplimiento normativo que dominan las principales competencias en auditor\u00eda pr\u00e1ctica y sistemas de gesti\u00f3n.","og_url":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/","og_site_name":"AEROTHRIVE","article_modified_time":"2026-05-06T13:46:12+00:00","og_image":[{"width":2560,"height":1470,"url":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/IMG_5013-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/","url":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/","name":"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145 | AEROTHRIVE","isPartOf":{"@id":"https:\/\/aerothrive.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/#primaryimage"},"image":{"@id":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/#primaryimage"},"thumbnailUrl":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/IMG_5013-scaled.jpg","datePublished":"2023-11-08T15:56:23+00:00","dateModified":"2026-05-06T13:46:12+00:00","breadcrumb":{"@id":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/#primaryimage","url":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/IMG_5013-scaled.jpg","contentUrl":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/03\/IMG_5013-scaled.jpg","width":2560,"height":1470},{"@type":"BreadcrumbList","@id":"https:\/\/aerothrive.com\/es\/diploma\/diploma-de-experto-en-gestion-de-seguridad-parte-145\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aerothrive.com\/es\/"},{"@type":"ListItem","position":2,"name":"Diploma de Experto en Gesti\u00f3n de Seguridad Parte 145"}]},{"@type":"WebSite","@id":"https:\/\/aerothrive.com\/es\/#website","url":"https:\/\/aerothrive.com\/es\/","name":"AEROTHRIVE","description":"Global Aviation Excellence","publisher":{"@id":"https:\/\/aerothrive.com\/es\/#organization"},"alternateName":"AEROTHRIVE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aerothrive.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/aerothrive.com\/es\/#organization","name":"AEROTHRIVE GmbH","url":"https:\/\/aerothrive.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/aerothrive.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/aerothrive-logo.png","contentUrl":"https:\/\/aerothrive.com\/wp-content\/uploads\/2024\/01\/aerothrive-logo.png","width":3508,"height":2480,"caption":"AEROTHRIVE GmbH"},"image":{"@id":"https:\/\/aerothrive.com\/es\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/f4_diploma\/38959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/f4_diploma"}],"about":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/types\/f4_diploma"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/media\/38960"}],"wp:attachment":[{"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/media?parent=38959"}],"wp:term":[{"taxonomy":"f4_tax_type","embeddable":true,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/f4_tax_type?post=38959"},{"taxonomy":"f4_tax_category","embeddable":true,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/f4_tax_category?post=38959"},{"taxonomy":"f4_tax_industry","embeddable":true,"href":"https:\/\/aerothrive.com\/es\/wp-json\/wp\/v2\/f4_tax_industry?post=38959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}